{"id":11834,"date":"2020-03-17T18:00:26","date_gmt":"2020-03-17T17:00:26","guid":{"rendered":"https:\/\/fleurette-constructeur.s1te.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg"},"modified":"2020-03-17T18:00:55","modified_gmt":"2020-03-17T17:00:55","slug":"camping-car-visite-usine-story-fleurette-constructeur-2","status":"inherit","type":"attachment","link":"https:\/\/www.fleurette-constructeur.fr\/en\/our-story\/camping-car-visite-usine-story-fleurette-constructeur-2\/","title":{"rendered":"camping-car-visite-usine-story-fleurette-constructeur"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-11834","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>camping-car-visite-usine-story-fleurette-constructeur - Fleurette Constructeur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"camping-car-visite-usine-story-fleurette-constructeur - Fleurette Constructeur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Fleurette Constructeur\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fleurette-Florium-Motorhomes-229400777088532\/?fref=ts\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-17T17:00:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"495\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FleuretteCC\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fleurette-constructeur.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/camping-car-visite-usine-story-fleurette-constructeur.jpg\",\"url\":\"https:\\\/\\\/www.fleurette-constructeur.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/camping-car-visite-usine-story-fleurette-constructeur.jpg\",\"name\":\"camping-car-visite-usine-story-fleurette-constructeur - Fleurette Constructeur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fleurette-constructeur.fr\\\/en\\\/#website\"},\"datePublished\":\"2020-03-17T17:00:26+00:00\",\"dateModified\":\"2020-03-17T17:00:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fleurette-constructeur.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/camping-car-visite-usine-story-fleurette-constructeur.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fleurette-constructeur.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/camping-car-visite-usine-story-fleurette-constructeur.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fleurette-constructeur.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/camping-car-visite-usine-story-fleurette-constructeur.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fleurette-constructeur.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our story\",\"item\":\"https:\\\/\\\/www.fleurette-constructeur.fr\\\/en\\\/our-story\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"camping-car-visite-usine-story-fleurette-constructeur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fleurette-constructeur.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.fleurette-constructeur.fr\\\/en\\\/\",\"name\":\"Fleurette Constructeur\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fleurette-constructeur.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"camping-car-visite-usine-story-fleurette-constructeur - Fleurette Constructeur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg","og_locale":"en_US","og_type":"article","og_title":"camping-car-visite-usine-story-fleurette-constructeur - Fleurette Constructeur","og_url":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg","og_site_name":"Fleurette Constructeur","article_publisher":"https:\/\/www.facebook.com\/Fleurette-Florium-Motorhomes-229400777088532\/?fref=ts","article_modified_time":"2020-03-17T17:00:55+00:00","og_image":[{"width":1400,"height":495,"url":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@FleuretteCC","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg","url":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg","name":"camping-car-visite-usine-story-fleurette-constructeur - Fleurette Constructeur","isPartOf":{"@id":"https:\/\/www.fleurette-constructeur.fr\/en\/#website"},"datePublished":"2020-03-17T17:00:26+00:00","dateModified":"2020-03-17T17:00:55+00:00","breadcrumb":{"@id":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fleurette-constructeur.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Our story","item":"https:\/\/www.fleurette-constructeur.fr\/en\/our-story\/"},{"@type":"ListItem","position":3,"name":"camping-car-visite-usine-story-fleurette-constructeur"}]},{"@type":"WebSite","@id":"https:\/\/www.fleurette-constructeur.fr\/en\/#website","url":"https:\/\/www.fleurette-constructeur.fr\/en\/","name":"Fleurette Constructeur","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fleurette-constructeur.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"106\" src=\"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-300x106.jpg\" class=\"attachment-medium size-medium\" alt=\"camping-car - visite usine - story - fleurette constructeur\" srcset=\"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-300x106.jpg 300w, https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-1024x362.jpg 1024w, https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-768x272.jpg 768w, https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg 1400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p class=\"attachment\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"106\" src=\"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-300x106.jpg\" class=\"attachment-medium size-medium\" alt=\"camping-car - visite usine - story - fleurette constructeur\" srcset=\"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-300x106.jpg 300w, https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-1024x362.jpg 1024w, https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-768x272.jpg 768w, https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg 1400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n"},"alt_text":"camping-car - visite usine - story - fleurette constructeur","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1400,"height":495,"file":"2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg","sizes":{"medium":{"file":"camping-car-visite-usine-story-fleurette-constructeur-300x106.jpg","width":300,"height":106,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-300x106.jpg"},"large":{"file":"camping-car-visite-usine-story-fleurette-constructeur-1024x362.jpg","width":1024,"height":362,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-1024x362.jpg"},"thumbnail":{"file":"camping-car-visite-usine-story-fleurette-constructeur-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-150x150.jpg"},"medium_large":{"file":"camping-car-visite-usine-story-fleurette-constructeur-768x272.jpg","width":768,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-768x272.jpg"},"large_featured_image":{"file":"camping-car-visite-usine-story-fleurette-constructeur-1170x250.jpg","width":1170,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur-1170x250.jpg"},"full":{"file":"camping-car-visite-usine-story-fleurette-constructeur.jpg","width":1400,"height":495,"mime_type":"image\/jpeg","source_url":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":4245,"source_url":"https:\/\/www.fleurette-constructeur.fr\/wp-content\/uploads\/2020\/03\/camping-car-visite-usine-story-fleurette-constructeur.jpg","_links":{"self":[{"href":"https:\/\/www.fleurette-constructeur.fr\/en\/wp-json\/wp\/v2\/media\/11834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fleurette-constructeur.fr\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.fleurette-constructeur.fr\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.fleurette-constructeur.fr\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fleurette-constructeur.fr\/en\/wp-json\/wp\/v2\/comments?post=11834"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":4245,"href":"https:\/\/www.fleurette-constructeur.fr\/en\/wp-json\/wp\/v2\/pages\/4245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}